{"id":805,"date":"2018-07-06T16:19:00","date_gmt":"2018-07-06T13:19:00","guid":{"rendered":"https:\/\/www.colegioaltamira.com.ar\/sitio\/acto-9-de-julio\/"},"modified":"2018-07-06T16:19:00","modified_gmt":"2018-07-06T13:19:00","slug":"acto-9-de-julio","status":"publish","type":"post","link":"https:\/\/www.colegioaltamira.com.ar\/sitio\/acto-9-de-julio\/","title":{"rendered":"Acto 9 de julio"},"content":{"rendered":"<table style=\"width: 643px;\" border=\"0\">\n<tbody>\n<tr style=\"height: 32px;\">\n<td style=\"width: 633px; height: 32px;\" colspan=\"2\">\n<h2 style=\"margin-top: 0px; margin-bottom: 0px; padding-bottom: 0px; text-align: center;\">Conmemoramos el D&iacute;a de la Independencia<\/h2>\n<\/td>\n<\/tr>\n<tr style=\"height: 41px;\">\n<td style=\"width: 633px; text-align: justify; height: 41px;\" colspan=\"2\">El d&iacute;a viernes 6 de julio se llev&oacute; a cabo el acto en conmemoraci&oacute;n del d&iacute;a de la independencia, en los 3 niveles de la instituci&oacute;n<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"width: 633px; height: 23px;\" colspan=\"2\">&nbsp;<\/td>\n<\/tr>\n<tr style=\"height: 26px;\">\n<td style=\"width: 280px; height: 26px;\">\n<h3 style=\"margin-top: 0px; margin-bottom: 0px; padding-bottom: 0px; text-align: center;\"><a href=\"#1\">Inicial y primario<\/a><\/h3>\n<\/td>\n<td style=\"width: 347px; height: 26px;\">\n<h3 style=\"margin-top: 0px; margin-bottom: 0px; padding-bottom: 0px; text-align: center;\"><a href=\"#2\">Secundario<\/a><\/h3>\n<\/td>\n<\/tr>\n<tr style=\"height: 176px;\">\n<td style=\"width: 280px; height: 176px;\">\n<div style=\"text-align: center;\"><img decoding=\"async\" loading=\"lazy\" width=\"280\" height=\"171\" style=\"vertical-align: middle;\" src=\"https:\/\/www.colegioaltamira.com.ar\/aula\/archivos\/repositorio\/500\/577\/acto_primjar.jpeg\" alt=\"\" border=\"0\"><\/div>\n<\/td>\n<td style=\"width: 347px; height: 176px;\">\n<div style=\"text-align: center;\"><img decoding=\"async\" loading=\"lazy\" width=\"280\" height=\"170\" style=\"vertical-align: middle;\" src=\"https:\/\/www.colegioaltamira.com.ar\/aula\/archivos\/repositorio\/500\/576\/acto_sec.jpeg\" alt=\"\" border=\"0\"><\/div>\n<\/td>\n<\/tr>\n<tr style=\"height: 110px;\">\n<td style=\"width: 280px; text-align: center; vertical-align: middle; height: 110px;\">\n<p style=\"padding-left: 30px; text-align: justify;\">Los niveles inicial y primario realizaron el acto en forma conjunta, presentando diferentes actividades. Finalizado el mismo se invit&oacute; a recorrer los murales con fotos de la escuela de ayer y de hoy.<\/p>\n<\/td>\n<td style=\"width: 347px; padding-left: 30px; height: 110px; text-align: justify;\">Secundario conmemor&oacute; el d&iacute;a con una actividad al finalizar las palabras alusivas. La misma consisti&oacute; en la participaci&oacute;n en un juego de preguntas y respuestas mediante la app Kahoot.&nbsp;<\/td>\n<\/tr>\n<tr style=\"height: 9px;\">\n<td style=\"width: 633px; height: 9px; text-align: center;\" colspan=\"2\"><span style=\"font-size: 12pt;\"><strong>Los bailes no faltaron<\/strong><\/span><\/td>\n<\/tr>\n<tr style=\"height: 43px;\">\n<td style=\"width: 633px; height: 43px;\">\n<p style=\"text-align: justify;\"><video width=\"357\" height=\"186\" style=\"vertical-align: middle;\" controls><source src=\"https:\/\/www.colegioaltamira.com.ar\/aula\/archivos\/repositorio\/500\/580\/bailes.mp4\" type=\"video\/mp4\"><\/source><\/video><\/p>\n<\/td>\n<td style=\"width: 633px; height: 43px;\">\n<p style=\"text-align: justify; padding-left: 30px;\">Durante el acto, alumnos de 6 A y B bailaron un Peric&oacute;n y el Carnavalito. Por su parte, sala de 4 present&oacute; un n&uacute;mero de expresi&oacute;n corporal.<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" width=\"195\" height=\"119\" style=\"vertical-align: middle; display: block; margin-left: auto; margin-right: auto;\" src=\"https:\/\/www.colegioaltamira.com.ar\/aula\/archivos\/repositorio\/500\/581\/teatralizacion1.jpeg\" alt=\"\" border=\"0\"><\/p>\n<\/td>\n<\/tr>\n<tr style=\"height: 9px;\">\n<td style=\"width: 633px; height: 9px;\" colspan=\"2\">&nbsp;<\/td>\n<\/tr>\n<tr style=\"height: 26px;\">\n<td style=\"width: 633px; height: 26px;\" colspan=\"2\">\n<h3 style=\"margin-top: 0px; margin-bottom: 0px; padding-bottom: 0px; text-align: center;\"><span style=\"background-color: #d5d5d5;\">Cocinamos tortafritas<\/span><\/h3>\n<\/td>\n<\/tr>\n<tr style=\"height: 181px;\">\n<td style=\"width: 283px; height: 181px; text-align: justify;\">Para finalizar, se degust&oacute; leche chocolatada y tortafritas elaboradas por alumnos de 6to a&ntilde;o de secundaria y maternal del nivel inicial. Agradecemos al profesor del taller de cocina Leonardo Lopez por el asesoramiento y orientaci&oacute;n.<\/td>\n<td style=\"width: 344px; height: 181px;\">\n<div style=\"text-align: center;\"><video width=\"338\" height=\"176\" style=\"vertical-align: middle;\" controls><source src=\"https:\/\/www.colegioaltamira.com.ar\/aula\/archivos\/repositorio\/500\/578\/Festejamos_con_tortafritas.mp4\" type=\"video\/mp4\"><\/source><\/video><\/div>\n<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"width: 633px; height: 23px; text-align: center;\" colspan=\"2\">&nbsp;<span style=\"font-size: 12pt;\"><strong>Mural \u00abAyer y hoy\u00bb<\/strong><\/span><\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"width: 633px; height: 23px;\" colspan=\"2\">&nbsp;<img decoding=\"async\" loading=\"lazy\" width=\"338\" height=\"259\" style=\"vertical-align: middle; display: block; margin-left: auto; margin-right: auto;\" src=\"https:\/\/www.colegioaltamira.com.ar\/aula\/archivos\/repositorio\/500\/582\/ayer_y_hoy.gif\" alt=\"\" border=\"0\"><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>Conmemoramos el D&iacute;a de la Independencia El d&iacute;a viernes 6 de julio se llev&oacute; a cabo el acto en conmemoraci&oacute;n del d&iacute;a de la independencia, en los 3 niveles de la instituci&oacute;n &nbsp; Inicial y primario Secundario Los niveles inicial y primario realizaron el acto en forma conjunta, presentando diferentes actividades. Finalizado el mismo se &#8230; <a title=\"Acto 9 de julio\" class=\"read-more\" href=\"https:\/\/www.colegioaltamira.com.ar\/sitio\/acto-9-de-julio\/\" aria-label=\"More on Acto 9 de julio\">[+]<\/a><\/p>\n","protected":false},"author":1449,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[9],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.colegioaltamira.com.ar\/sitio\/wp-json\/wp\/v2\/posts\/805"}],"collection":[{"href":"https:\/\/www.colegioaltamira.com.ar\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.colegioaltamira.com.ar\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.colegioaltamira.com.ar\/sitio\/wp-json\/wp\/v2\/users\/1449"}],"replies":[{"embeddable":true,"href":"https:\/\/www.colegioaltamira.com.ar\/sitio\/wp-json\/wp\/v2\/comments?post=805"}],"version-history":[{"count":0,"href":"https:\/\/www.colegioaltamira.com.ar\/sitio\/wp-json\/wp\/v2\/posts\/805\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.colegioaltamira.com.ar\/sitio\/wp-json\/wp\/v2\/media?parent=805"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.colegioaltamira.com.ar\/sitio\/wp-json\/wp\/v2\/categories?post=805"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.colegioaltamira.com.ar\/sitio\/wp-json\/wp\/v2\/tags?post=805"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}