{"id":1823,"date":"2019-09-05T11:01:10","date_gmt":"2019-09-05T14:01:10","guid":{"rendered":"https:\/\/www.colegioaltamira.com.ar\/sitio\/?p=1823"},"modified":"2019-09-05T14:01:06","modified_gmt":"2019-09-05T17:01:06","slug":"elecciones-de-proceres-en-nivel-primario","status":"publish","type":"post","link":"https:\/\/www.colegioaltamira.com.ar\/sitio\/elecciones-de-proceres-en-nivel-primario\/","title":{"rendered":"Elecciones de pr\u00f3ceres en nivel primario"},"content":{"rendered":"<p>El lunes 12 de agosto y en el marco de un proyecto del \u00e1rea de Ciencias Sociales titulado \u00abCampa\u00f1a de pr\u00f3ceres\u00bb , los alumnos de 6to a\u00f1o A y\u00a0 B de la instituci\u00f3n, Nivel Primario,\u00a0 realizaron una elecci\u00f3n del Pr\u00f3cer con la orientaci\u00f3n de las docentes Karina Iba\u00f1ez y Jimena Marquez. El objetivo del proyecto fue que los alumnos pudiesen vivenciar la experiencia\u00a0 que implica el desarrollo de elecciones democr\u00e1ticas.<\/p>\n<p>El Proyecto Campa\u00f1a de Pr\u00f3ceres fue desarrollado a partir de dos \u00e1reas integradas: Cs. Sociales y Pr\u00e1cticas del Lenguaje.<\/p>\n<p>Se abordaron los contenidos de ambas \u00e1reas haciendo el recorte: los aportes de ciertos actores sociales en la consolidaci\u00f3n del Estado argentino. Quedaron seleccionados por los chicos 15 pr\u00f3ceres, se realizaron investigaciones sobre ellos y se comparti\u00f3 la informaci\u00f3n. Luego trabajaron en Pr\u00e1cticas del lenguaje la argumentaci\u00f3n (en principio con publicidades y propagandas) para poco a poco ir animando a los alumnos a debatir y argumentar por qu\u00e9 eleg\u00edan a determinados pr\u00f3ceres como significativos o influyentes para nuestra historia. Ya en \u00abcampa\u00f1a\u00bb cada alumno \u00abdefendi\u00f3\u00bb con argumentos a dos pr\u00f3ceres (para despistar) y lograr con sus fundamentos convencer a los compa\u00f1eros de que deb\u00edan votar por determinado actor social.<\/p>\n<p>Luego de todo este trabajo, los chicos confeccionaron las boletas de todos los candidatos, el padr\u00f3n electoral, sobres y los \u00abDNI\u00bb. Finalmente el lunes 12\/8 se realiz\u00f3 la elecci\u00f3n con cuarto oscuro, urnas y presidentes de mesa. Al terminar este proceso se prosigui\u00f3 al escrutinio que fue totalmente transparente (un alumno sacaba los sobres y cantaba los votos mientras otro escrib\u00eda en un afiche).<\/p>\n<p>El ganador result\u00f3 Jos\u00e9 de San Mart\u00edn con un total de 28 votos de 47 . Sacaron el porcentaje, siendo \u00e9ste de 59,5 %.<\/p>\n<p>La actividad fue muy grata durante todo el proceso ya que todos estuvieron comprometidos y esperando la definici\u00f3n de \u00abel mejor pr\u00f3cer\u00bb como finalmente lo llamaron.<\/p>\n<p>&nbsp;<\/p>\n<div id='gallery-1' class='gallery galleryid-1823 gallery-columns-3 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.colegioaltamira.com.ar\/sitio\/elecciones-de-proceres-en-nivel-primario\/7bf4a14f-8c4b-432a-8706-695ce3888ac4\/#main'><img width=\"500\" height=\"500\" src=\"https:\/\/www.colegioaltamira.com.ar\/sitio\/wp-content\/uploads\/2019\/08\/7bf4a14f-8c4b-432a-8706-695ce3888ac4-500x500.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.colegioaltamira.com.ar\/sitio\/elecciones-de-proceres-en-nivel-primario\/4335d817-11e6-440d-bcc0-b0cd59d99fe3\/#main'><img width=\"500\" height=\"500\" src=\"https:\/\/www.colegioaltamira.com.ar\/sitio\/wp-content\/uploads\/2019\/08\/4335d817-11e6-440d-bcc0-b0cd59d99fe3-500x500.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El lunes 12 de agosto y en el marco de un proyecto del \u00e1rea de Ciencias Sociales titulado \u00abCampa\u00f1a de pr\u00f3ceres\u00bb , los alumnos de 6to a\u00f1o A y\u00a0 B de la instituci\u00f3n, Nivel Primario,\u00a0 realizaron una elecci\u00f3n del Pr\u00f3cer con la orientaci\u00f3n de las docentes Karina Iba\u00f1ez y Jimena Marquez. El objetivo del proyecto &#8230; <a title=\"Elecciones de pr\u00f3ceres en nivel primario\" class=\"read-more\" href=\"https:\/\/www.colegioaltamira.com.ar\/sitio\/elecciones-de-proceres-en-nivel-primario\/\" aria-label=\"More on Elecciones de pr\u00f3ceres en nivel primario\">[+]<\/a><\/p>\n","protected":false},"author":1434,"featured_media":1826,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[26],"acf":[],"_links":{"self":[{"href":"https:\/\/www.colegioaltamira.com.ar\/sitio\/wp-json\/wp\/v2\/posts\/1823"}],"collection":[{"href":"https:\/\/www.colegioaltamira.com.ar\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.colegioaltamira.com.ar\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.colegioaltamira.com.ar\/sitio\/wp-json\/wp\/v2\/users\/1434"}],"replies":[{"embeddable":true,"href":"https:\/\/www.colegioaltamira.com.ar\/sitio\/wp-json\/wp\/v2\/comments?post=1823"}],"version-history":[{"count":4,"href":"https:\/\/www.colegioaltamira.com.ar\/sitio\/wp-json\/wp\/v2\/posts\/1823\/revisions"}],"predecessor-version":[{"id":1847,"href":"https:\/\/www.colegioaltamira.com.ar\/sitio\/wp-json\/wp\/v2\/posts\/1823\/revisions\/1847"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.colegioaltamira.com.ar\/sitio\/wp-json\/wp\/v2\/media\/1826"}],"wp:attachment":[{"href":"https:\/\/www.colegioaltamira.com.ar\/sitio\/wp-json\/wp\/v2\/media?parent=1823"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.colegioaltamira.com.ar\/sitio\/wp-json\/wp\/v2\/categories?post=1823"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.colegioaltamira.com.ar\/sitio\/wp-json\/wp\/v2\/tags?post=1823"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}