{"id":1825,"date":"2019-08-23T15:23:02","date_gmt":"2019-08-23T18:23:02","guid":{"rendered":"https:\/\/www.colegioaltamira.com.ar\/sitio\/wp-content\/uploads\/2019\/08\/4335d817-11e6-440d-bcc0-b0cd59d99fe3.jpg"},"modified":"2019-08-23T15:23:02","modified_gmt":"2019-08-23T18:23:02","slug":"4335d817-11e6-440d-bcc0-b0cd59d99fe3","status":"inherit","type":"attachment","link":"https:\/\/www.colegioaltamira.com.ar\/sitio\/elecciones-de-proceres-en-nivel-primario\/4335d817-11e6-440d-bcc0-b0cd59d99fe3\/#main","title":{"rendered":"4335d817-11e6-440d-bcc0-b0cd59d99fe3"},"author":1434,"comment_status":"open","ping_status":"closed","template":"","meta":[],"acf":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.colegioaltamira.com.ar\/sitio\/wp-content\/uploads\/2019\/08\/4335d817-11e6-440d-bcc0-b0cd59d99fe3.jpg'><img width=\"1000\" height=\"562\" src=\"https:\/\/www.colegioaltamira.com.ar\/sitio\/wp-content\/uploads\/2019\/08\/4335d817-11e6-440d-bcc0-b0cd59d99fe3-1000x562.jpg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/www.colegioaltamira.com.ar\/sitio\/wp-content\/uploads\/2019\/08\/4335d817-11e6-440d-bcc0-b0cd59d99fe3-1000x562.jpg 1000w, https:\/\/www.colegioaltamira.com.ar\/sitio\/wp-content\/uploads\/2019\/08\/4335d817-11e6-440d-bcc0-b0cd59d99fe3-768x431.jpg 768w, https:\/\/www.colegioaltamira.com.ar\/sitio\/wp-content\/uploads\/2019\/08\/4335d817-11e6-440d-bcc0-b0cd59d99fe3.jpg 1040w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1040,"height":584,"file":"2019\/08\/4335d817-11e6-440d-bcc0-b0cd59d99fe3.jpg","sizes":{"thumbnail":{"file":"4335d817-11e6-440d-bcc0-b0cd59d99fe3-500x500.jpg","width":500,"height":500,"mime_type":"image\/jpeg","source_url":"https:\/\/www.colegioaltamira.com.ar\/sitio\/wp-content\/uploads\/2019\/08\/4335d817-11e6-440d-bcc0-b0cd59d99fe3-500x500.jpg"},"medium":{"file":"4335d817-11e6-440d-bcc0-b0cd59d99fe3-1000x562.jpg","width":1000,"height":562,"mime_type":"image\/jpeg","source_url":"https:\/\/www.colegioaltamira.com.ar\/sitio\/wp-content\/uploads\/2019\/08\/4335d817-11e6-440d-bcc0-b0cd59d99fe3-1000x562.jpg"},"medium_large":{"file":"4335d817-11e6-440d-bcc0-b0cd59d99fe3-768x431.jpg","width":768,"height":431,"mime_type":"image\/jpeg","source_url":"https:\/\/www.colegioaltamira.com.ar\/sitio\/wp-content\/uploads\/2019\/08\/4335d817-11e6-440d-bcc0-b0cd59d99fe3-768x431.jpg"},"full":{"file":"4335d817-11e6-440d-bcc0-b0cd59d99fe3.jpg","width":1040,"height":584,"mime_type":"image\/jpeg","source_url":"https:\/\/www.colegioaltamira.com.ar\/sitio\/wp-content\/uploads\/2019\/08\/4335d817-11e6-440d-bcc0-b0cd59d99fe3.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":1823,"source_url":"https:\/\/www.colegioaltamira.com.ar\/sitio\/wp-content\/uploads\/2019\/08\/4335d817-11e6-440d-bcc0-b0cd59d99fe3.jpg","_links":{"self":[{"href":"https:\/\/www.colegioaltamira.com.ar\/sitio\/wp-json\/wp\/v2\/media\/1825"}],"collection":[{"href":"https:\/\/www.colegioaltamira.com.ar\/sitio\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.colegioaltamira.com.ar\/sitio\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.colegioaltamira.com.ar\/sitio\/wp-json\/wp\/v2\/users\/1434"}],"replies":[{"embeddable":true,"href":"https:\/\/www.colegioaltamira.com.ar\/sitio\/wp-json\/wp\/v2\/comments?post=1825"}]}}